{"id":356,"date":"2021-12-15T11:49:00","date_gmt":"2021-12-15T10:49:00","guid":{"rendered":"https:\/\/graine-de-loute.ovh\/?p=356"},"modified":"2021-08-13T11:54:01","modified_gmt":"2021-08-13T09:54:01","slug":"chaignay-sous-la-neige","status":"publish","type":"post","link":"https:\/\/graine-de-loute.ovh\/index.php\/2021\/12\/15\/chaignay-sous-la-neige\/","title":{"rendered":"Chaignay sous la neige"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"361\" data-permalink=\"https:\/\/graine-de-loute.ovh\/26705807518_78ec0cd763_o-scaled\/\" data-orig-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1.jpg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ONEPLUS A5010&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1520010854&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.103000164032&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"26705807518_78ec0cd763_o-scaled\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-1024x768.jpg\" src=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-1024x768.jpg\" alt=\"\" data-id=\"361\" data-full-url=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1.jpg\" data-link=\"https:\/\/graine-de-loute.ovh\/26705807518_78ec0cd763_o-scaled\/\" class=\"wp-image-361\" srcset=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-1024x768.jpg 1024w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-300x225.jpg 300w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-768x576.jpg 768w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-1536x1152.jpg 1536w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-2048x1536.jpg 2048w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-600x450.jpg 600w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705807518_78ec0cd763_o-scaled-1-945x709.jpg 945w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"360\" data-permalink=\"https:\/\/graine-de-loute.ovh\/26705652958_040f4c8fac_o-scaled\/\" data-orig-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1.jpg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ONEPLUS A5010&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1519923930&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.103&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.00040633888663145&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"26705652958_040f4c8fac_o-scaled\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-1024x768.jpg\" src=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-1024x768.jpg\" alt=\"\" data-id=\"360\" data-full-url=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1.jpg\" data-link=\"https:\/\/graine-de-loute.ovh\/26705652958_040f4c8fac_o-scaled\/\" class=\"wp-image-360\" srcset=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-1024x768.jpg 1024w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-300x225.jpg 300w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-768x576.jpg 768w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-1536x1152.jpg 1536w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-2048x1536.jpg 2048w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-600x450.jpg 600w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705652958_040f4c8fac_o-scaled-1-945x709.jpg 945w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"359\" data-permalink=\"https:\/\/graine-de-loute.ovh\/40577167741_41cf7976de_o-scaled\/\" data-orig-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1.jpg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ONEPLUS A5010&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1519922619&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.103&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.00068306010928962&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"40577167741_41cf7976de_o-scaled\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-1024x768.jpg\" src=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-1024x768.jpg\" alt=\"\" data-id=\"359\" data-full-url=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1.jpg\" data-link=\"https:\/\/graine-de-loute.ovh\/40577167741_41cf7976de_o-scaled\/\" class=\"wp-image-359\" srcset=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-1024x768.jpg 1024w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-300x225.jpg 300w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-768x576.jpg 768w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-1536x1152.jpg 1536w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-2048x1536.jpg 2048w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-600x450.jpg 600w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/40577167741_41cf7976de_o-scaled-1-945x709.jpg 945w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" data-attachment-id=\"358\" data-permalink=\"https:\/\/graine-de-loute.ovh\/39682620755_7af41ef843_o-scaled\/\" data-orig-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1.jpg\" data-orig-size=\"2560,1321\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ONEPLUS A5010&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1519921900&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.103&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.00033244680851064&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"39682620755_7af41ef843_o-scaled\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-1024x528.jpg\" src=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-1024x528.jpg\" alt=\"\" data-id=\"358\" data-full-url=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1.jpg\" data-link=\"https:\/\/graine-de-loute.ovh\/39682620755_7af41ef843_o-scaled\/\" class=\"wp-image-358\" srcset=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-1024x528.jpg 1024w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-300x155.jpg 300w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-768x396.jpg 768w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-1536x793.jpg 1536w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-2048x1057.jpg 2048w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-600x310.jpg 600w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1-945x488.jpg 945w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"357\" data-permalink=\"https:\/\/graine-de-loute.ovh\/26705666888_b4f66e771d_o-scaled\/\" data-orig-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1.jpg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ONEPLUS A5010&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1519922254&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.103&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.00036941263391208&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"26705666888_b4f66e771d_o-scaled\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-1024x768.jpg\" src=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-1024x768.jpg\" alt=\"\" data-id=\"357\" data-full-url=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1.jpg\" data-link=\"https:\/\/graine-de-loute.ovh\/26705666888_b4f66e771d_o-scaled\/\" class=\"wp-image-357\" srcset=\"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-1024x768.jpg 1024w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-300x225.jpg 300w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-768x576.jpg 768w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-1536x1152.jpg 1536w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-2048x1536.jpg 2048w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-600x450.jpg 600w, https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/26705666888_b4f66e771d_o-scaled-1-945x709.jpg 945w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[],"class_list":["post-356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photographie"],"jetpack_featured_media_url":"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/39682620755_7af41ef843_o-scaled-1.jpg","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdhhZc-5K","_links":{"self":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":0,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts\/356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/media\/358"}],"wp:attachment":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}