{"id":292,"date":"2021-08-10T18:09:01","date_gmt":"2021-08-10T16:09:01","guid":{"rendered":"https:\/\/graine-de-loute.ovh\/?p=292"},"modified":"2021-08-10T21:04:47","modified_gmt":"2021-08-10T19:04:47","slug":"inconsolable","status":"publish","type":"post","link":"https:\/\/graine-de-loute.ovh\/index.php\/2021\/08\/10\/inconsolable\/","title":{"rendered":"Inconsolable"},"content":{"rendered":"\n<p class=\"has-text-align-center\">J&rsquo;ai le coeur gros comme une pierre<\/p>\n\n\n\n<p class=\"has-text-align-center\">Les larmes ne cessent de couler<\/p>\n\n\n\n<p class=\"has-text-align-center\">J&rsquo;ai dans la bouche un go\u00fbt amer<\/p>\n\n\n\n<p class=\"has-text-align-center\">Qui me donne la naus\u00e9e<\/p>\n\n\n\n<p class=\"has-text-align-center\">Mon corps est secou\u00e9 de sanglots<\/p>\n\n\n\n<p class=\"has-text-align-center\">Rien ne peut les arr\u00eater<\/p>\n\n\n\n<p class=\"has-text-align-center\">J&rsquo;ai dans ma voix des tr\u00e9molos<\/p>\n\n\n\n<p class=\"has-text-align-center\">Qui m&#8217;emp\u00eachent de parler<\/p>\n\n\n\n<p class=\"has-text-align-center\">J&rsquo;ai la gorge serr\u00e9e et la poitrine compress\u00e9e<\/p>\n\n\n\n<p class=\"has-text-align-center\">Dans mon ventre tout est nou\u00e9<\/p>\n\n\n\n<p class=\"has-text-align-center\">Mon \u00eatre a mal et mon \u00e2me pleure<\/p>\n\n\n\n<p class=\"has-text-align-center\">Tout en moi n&rsquo;est qu&rsquo;une inconsolable douleur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai le coeur gros comme une pierre Les larmes ne cessent de couler J&rsquo;ai dans la bouche un go\u00fbt amer Qui me donne la naus\u00e9e Mon corps est secou\u00e9 de sanglots Rien ne peut les arr\u00eater J&rsquo;ai dans ma voix&#8230; <a class=\"more-link\" href=\"https:\/\/graine-de-loute.ovh\/index.php\/2021\/08\/10\/inconsolable\/\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[20],"tags":[27],"class_list":["post-292","post","type-post","status-publish","format-standard","hentry","category-poesie","tag-douleur"],"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdhhZc-4I","_links":{"self":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts\/292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=292"}],"version-history":[{"count":0,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts\/292\/revisions"}],"wp:attachment":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}