{"id":284,"date":"2021-08-09T13:06:24","date_gmt":"2021-08-09T11:06:24","guid":{"rendered":"https:\/\/graine-de-loute.ovh\/?p=284"},"modified":"2021-08-10T21:04:57","modified_gmt":"2021-08-10T19:04:57","slug":"les-aventures-du-pti-guillaume-la-partie-de-peche","status":"publish","type":"post","link":"https:\/\/graine-de-loute.ovh\/index.php\/2021\/08\/09\/les-aventures-du-pti-guillaume-la-partie-de-peche\/","title":{"rendered":"Les aventures du P&rsquo;ti Guillaume: la partie de p\u00eache"},"content":{"rendered":"\n<p><strong>L<\/strong>e p&rsquo;tit guillaume est un petit bonhomme de dix ans, aux cheveux blonds et aux yeux bruns. Dans sa vie, il n&rsquo;a pas trente-six hobbies. Ses passions: Star Wars, la p\u00eache et les vacances chez Ginette. Ginette, c&rsquo;est sa grand-m\u00e8re, une bonne dame de soixante-dix ans, adorable les jours o\u00f9 elle se l\u00e8ve de bonne humeur et tr\u00e8s coquette. Elle habite une contr\u00e9e lointaine qui porte le ravissant nom d&rsquo;Epinac. Le p&rsquo;tit Guillaume aime passer ses journ\u00e9es l\u00e0-bas, car il s&rsquo;agit d&rsquo;un endroit tout \u00e0 fait charmant au milieu duquel coule une petite rivi\u00e8re remplie de poissons. Justement, c&rsquo;est les vacances. Naturellement, le p&rsquo;tit Guillaume vient passer quelques jours chez sa grand-m\u00e8re.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Rien de tel pour se ressourcer et manger quelques bons petits plats: beefsteak et patates saut\u00e9es, hum, le p&rsquo;tit Guillaume adore. Puis hop, \u00e0 peine sorti de table, le voil\u00e0 parti canne \u00e0 p\u00eache en main, empruntant le chemin jusqu&rsquo;\u00e0 la petite rivi\u00e8re, son lieu pr\u00e9f\u00e9r\u00e9 \u00e0 Epinac. D&rsquo;ordinaire, il se serait repos\u00e9 apr\u00e8s d\u00e9jeuner et fait une sieste jusqu&rsquo;\u00e0 quinze heures en compagnie de sa grand-m\u00e8re, avant d&rsquo;aller jouer. Mais aujourd&rsquo;hui, le soleil est au rendez-vous et brille de mille feux. Le ciel est d&rsquo;un bleu \u00e0 couper le souffle. Les oiseaux chantent. Les papillons sont de sortie. Il ne fait pas froid du tout, mais la chaleur n&rsquo;est pas non plus \u00e9touffante. Le p&rsquo;tit Guillaume se sent simplement l&rsquo;envie d&rsquo;aller p\u00eacher et de l\u00e9zarder pr\u00e8s de la petite rivi\u00e8re o\u00f9 il pourrait sans doute tremper ses petits pieds de ch\u00e9rubin.Il ne suit pas le chemin jusqu&rsquo;au bout ceci-dit. Au contraire, il coupe \u00e0 travers les champs. Les vaches n&rsquo;ont pas encore \u00e9t\u00e9 install\u00e9es et de toute fa\u00e7on, le p&rsquo;tit Guillaume ne craint pas de se salir en passant par dessous les fils barbel\u00e9s ni de s&rsquo;\u00e9corcher les genoux nus \u00e0 travers les ronces et les orties. Le p&rsquo;tit Guillaume, c&rsquo;est un aventurier. Traverser les pr\u00e9s lui donne l&rsquo;impression de vivre d&rsquo;incroyables aventures: course- poursuite avec un fou furieux aux trousses, chute au pays de la nymphe de La Dr\u00e9e, rencontre avec le roi grenouille, l&rsquo;escalade de la montagne verte. Tant d&rsquo;histoires dont le p&rsquo;tit Guillaume est le h\u00e9ros. Mais enfin le voil\u00e0 qui arrive pr\u00e8s de la petite rivi\u00e8re bord\u00e9e d&rsquo;arbres. Il se trouve un bon coin, dresse sa canne \u00e0 p\u00eache et s&rsquo;allonge au pied d&rsquo;un arbre. Il a pris soin d&rsquo;enlever ses sabots afin que ses petits pieds puissent eux aussi prendre l&rsquo;air. Un bras sur les yeux ferm\u00e9s, il se laisse bercer par le doux bruit de l&rsquo;eau, le gazouillement des oiseaux et la brise agr\u00e9able du vent sur sa peau. Il reste ainsi quelques heures avant d&rsquo;\u00eatre d\u00e9rang\u00e9 par un nouveau venu. C&rsquo;est le p&rsquo;tit Gus ou plut\u00f4t le gros Gus, mais c&rsquo;est tout de m\u00eame un peu exag\u00e9r\u00e9, ou encore plut\u00f4t mal poli, de parler ainsi de lui, m\u00eame si ce n&rsquo;est pas loin de la v\u00e9rit\u00e9. Le p&rsquo;tit Gus est un petit gar\u00e7on de onze ans au ventre rond et aux cheveux courts. C&rsquo;est un bon copain. Comme le p&rsquo;tit<\/p>\n\n\n\n<p>Guillaume, il vient passer des vacances chez sa grand-m\u00e8re qui habite La Garenne, une autre commune d&rsquo;Epinac. La grand-m\u00e8re du p&rsquo;tit Gus vient souvent jouer \u00e0 la belote chez une de ses amies qui habite La Dr\u00e9e. Elle emm\u00e8ne toujours le p&rsquo;tit Gus avec elle. Cependant le p&rsquo;tit Gus ne compte pas la belote parmi ses occupations favorites. Comme le p&rsquo;tit Guillaume, le p&rsquo;tit Gus aime la p\u00eache. \u00c0 chaque fois qu&rsquo;il vient \u00e0 la Dr\u00e9e, il va se promener pr\u00e8s de la petite rivi\u00e8re. C&rsquo;est ainsi que le p&rsquo;tit Guillaume se trouve r\u00e9veill\u00e9 par le p&rsquo;tit Gus qui rit bien de la position de son jeune ami.<\/p>\n\n\n\n<p>\u00ab\u00a0C&rsquo;est ainsi que tu p\u00eaches p&rsquo;tit Guillaume. Et les poissons mordent ou ils fl\u00e2nent comme toi? Ils doivent bien rire l\u00e0 o\u00f9 ils sont. Je les vois d&rsquo;ici, le sourire aux l\u00e8vres \u00e0 s&rsquo;esclaffer &lsquo;venez,venez vite, tentez cette canne, vous ne vous y tromperez pas, personne ne vous attrapera, car le propri\u00e9taire l\u00e9zarde en ces lieux au pays des songes.\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Bonjour \u00e0 toi aussi p&rsquo;tit Gus. Qu&rsquo;est-ce qui t&rsquo;am\u00e8ne ici, la p\u00eache ou la moquerie?\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Allons, allons, calme-toi. Il faut bien rire un peu. Grand-m\u00e8re joue \u00e0 la belote avec sa bonne copine. Je viens ici pour trouver de l&rsquo;amusement et peut-\u00eatre un bon repas pour ce soir. Mais maintenant que je t&rsquo;ai trouv\u00e9, que dirais-tu d&rsquo;un concours? Celui qui attrape le plus de poissons gagne.\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Et qu&rsquo;ai-je \u00e0 y gagner?\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Une magnifique journ\u00e9e et un verre de limonade bien fra\u00eeche si je perds. Je sais que l&rsquo;amie de ma grand-m\u00e8re en a pr\u00e9par\u00e9 et elle ne rechigne pas \u00e0 en offrir.\u00a0\u00bb<\/p>\n\n\n\n<p>Le p&rsquo;tit Guillaume accepte avec un grand sourire. Il a grande envie de gagner ce petit jeu. Vite, il amorce sa canne \u00e0 p\u00eache, glisse un petit asticot et pfft, plonge la canne dans l&rsquo;eau. Le p&rsquo;tit Gus fait de m\u00eame. Mais les poissons ne mordent pas si facilement \u00e0 l&rsquo;hame\u00e7on. Ils ne sont pas fous. Ils ne tiennent pas vraiment \u00e0 finir frits \u00e0 la po\u00eale. Alors les gar\u00e7ons jettent des petits morceaux de viande et de ma\u00efs,esp\u00e9rant ainsi faire venir leurs d\u00e9licieuses victimes. Mais les poissons ne semblent pas bien affam\u00e9s. Peut-\u00eatre que d&rsquo;autres p\u00eacheurs sont venus les nourrir avant les enfants. Pour mettre un peu d&rsquo;ambiance, le p&rsquo;tit Guillaume tente un coup. L&rsquo;autre soir \u00e0 la t\u00e9l\u00e9vision, il a regard\u00e9 \u00ab\u00a0Ni vu ni connu\u00a0\u00bb, un film avec Louis de Fun\u00e8s, un p&rsquo;tit bonhomme presque chauve qui amuse bien son monde. L&rsquo;acteur incarne le r\u00f4le d&rsquo;un homme qui chasse et p\u00eache et distribue son gibier, ill\u00e9galement, aux gens de son village. Sa technique de p\u00eache a fort impressionn\u00e9 le p&rsquo;tit Guillaume et le chenapan veut utiliser le m\u00eame coup. Le p&rsquo;tit Guillaume tape du pied au sol, esp\u00e9rant qu&rsquo;un poisson sorte de l&rsquo;eau et vienne directement se poser \u00e0 ses pieds.<\/p>\n\n\n\n<p>\u00ab\u00a0Qu&rsquo;est-ce que tu fais p&rsquo;tit Guillaume?\u00a0\u00bbdemande le p&rsquo;tit Gus qui pense que son ami a d\u00fb prendre un coup de soleil.<\/p>\n\n\n\n<p>\u00ab\u00a0Bah! Tu vois bien\u00a0\u00bbdit le p&rsquo;tit Guillaume le plus s\u00e9rieusement du monde, avec sa petite langue qui sort de sa bouche, signe qu&rsquo;il est pleinement concentr\u00e9. \u00ab\u00a0Je tape du pied. J&rsquo;ai vu \u00e7a l&rsquo;autre soir \u00e0 la t\u00e9l\u00e9. Louis de Fun\u00e8s, il r\u00e9ussit \u00e0 chaque fois. Il a m\u00eame us\u00e9 de cette m\u00e9thode lors d&rsquo;un concours de p\u00eache.\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Et alors il a r\u00e9ussi?\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Pas seulement r\u00e9ussi, il a gagn\u00e9. Si lui y arrive, je peux le faire.\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Bonne id\u00e9e. Moi aussi je vais essayer. Euh, dis tu m&rsquo;en veux pas si je tente aussi? Je ne veux pas non plus te piquer ta m\u00e9thode.\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Non vas-y. Tu auras peut-\u00eatre plus de chance que moi\u00a0\u00bb Le p&rsquo;tit Gus tente lui aussi l&rsquo;exp\u00e9rience. Il tape du pied sur le sol esp\u00e9rant de tout c\u0153ur faire sortir un poisson. Mais rien ne sort. Les deux gar\u00e7ons tentent une fois. Deux fois. Trois fois. Inutile, cela ne sert \u00e0 rien. Les poissons pr\u00e9f\u00e8rent rester cach\u00e9s sous leurs rochers. Les enfants tirent une mine d\u00e9confite. Ils sont un peu tristes, surtout le p&rsquo;tit Guillaume, il croyait tellement que la prise de Louis de Fun\u00e8s fonctionnait.<\/p>\n\n\n\n<p>\u00ab\u00a0Bah peut-\u00eatre que seul Louis de Fun\u00e8s est capable d&rsquo;attraper les poissons de cette fa\u00e7on.\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Peut-\u00eatre.\u00a0\u00bb<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Suite \u00e0 cet \u00e9pisode, les deux gar\u00e7ons retournent chacun \u00e0 leur canne \u00e0 p\u00eache respective. Ils discutent pendant un moment de tout et de rien sans qu&rsquo;aucun poisson ne vienne les perturber. Au bout de quelque temps cependant, la canne du p&rsquo;tit Guillaume se met \u00e0 bouger. \u00ab\u00a0\u00c7a y est \u00e7a mord, j&rsquo;ai une prise.\u00a0\u00bb Le p&rsquo;tit Guillaume prend sa canne \u00e0 p\u00eache, il tire, il mouline, il ram\u00e8ne, il mouline, il ram\u00e8ne. Toutefois petit probl\u00e8me. Le molosse qui a mordu \u00e0 l&rsquo;app\u00e2t du p&rsquo;tit Guillaume semble \u00eatre un gros poisson et le p&rsquo;ti Guillaume peine \u00e0 le ramener. Il commence \u00e0 fatiguer, il est sur le point de se faire emporter, la ligne peut se briser \u00e0 tout moment. T\u00e9moin de la sc\u00e8ne, le p&rsquo;tit Gus contemple son ami en difficult\u00e9. \u00ab\u00a0Au diable le concours, les amis avant tout.\u00a0\u00bb Hop, ni une ni deux, voil\u00e0 le p&rsquo;tit Gus derri\u00e8re le p&rsquo;tit Guillaume. Ensemble ils tirent, ils tirent et ils tirent et plouf!!! Plouf!!! Les voil\u00e0 \u00e0 l&rsquo;eau. Le poisson a \u00e9t\u00e9 le plus fort. Il faut dire que c&rsquo;\u00e9tait un tr\u00e8s gros poison. Les enfants n&rsquo;ont pas eu le loisir de constater sa taille, mais c&rsquo;\u00e9tait assur\u00e9ment un tr\u00e8s, tr\u00e8s gros poisson. D&rsquo;ailleurs le voil\u00e0 au loin qui nage de toutes ses nageoires en riant aux d\u00e9pens des deux jeunes morveux qui ont eu l&rsquo;audace de vouloir le p\u00eacher. Les deux gar\u00e7ons sont un peu stup\u00e9faits. Que vient-il de se passer? Ils viennent de se faire avoir par un poisson. Quelle dr\u00f4le d&rsquo;id\u00e9e. La ligne a cass\u00e9. Et puis tant pis, l&rsquo;eau est bien bonne. Le p&rsquo;tit guillaume et le p&rsquo;tit Gus rient de bon c\u0153ur. Ce n&rsquo;est pas si grave. Ce n&rsquo;est qu&rsquo;un poisson apr\u00e8s tout. Qu&rsquo;il est agr\u00e9able d&rsquo;\u00eatre mouill\u00e9 par temps de chaleur. Voil\u00e0 tout \u00e0 coup les gar\u00e7ons emport\u00e9s dans une bataille d&rsquo;eau. Et vas-y que je te mouille. Finalement, le concours de p\u00eache est oubli\u00e9, c&rsquo;est \u00e0 celui qui sera le plus mouill\u00e9.Il se fait tard. Les gar\u00e7ons se sont bien amus\u00e9s, m\u00eame s&rsquo;ils rentrent bredouilles. Le p&rsquo;tit Guillaume accompagne un moment le p&rsquo;tit Gus chez l&rsquo;amie de sa grand-m\u00e8re o\u00f9 il se voit offrir un grand verre de limonade bien fra\u00eeche, tr\u00e8s plaisant pour sa gorge assoiff\u00e9e. Puis, apr\u00e8s avoir dit au revoir et merci, il rentre vite chez la Ginette qui l&rsquo;attend de pied ferme pour le souper. En le voyant, Ginette d\u00e9glutit. Son petit-fils est tout tremp\u00e9, tout d\u00e9peign\u00e9, on dirait un clodo.<\/p>\n\n\n\n<p>\u00ab\u00a0O\u00f9 es-tu pass\u00e9 p&rsquo;tit Guillaume? Regarde-moi ce que tu ressembles. Pire que mes vieux chiffons. Va vite prendre une douche, on va passer \u00e0 table.\u00a0\u00bb<\/p>\n\n\n\n<p>Aussit\u00f4t dit, aussit\u00f4t fait. Le p&rsquo;tit Guillaume se h\u00e2te de prendre une douche, de passer un pyjama et de rejoindre sa mamie Ginette \u00e0 table. La bonne dame n&rsquo;est d\u00e9j\u00e0 plus f\u00e2ch\u00e9e. Comment le rester quand on a un petit-fils avec une frimousse d&rsquo;ange! Pendant le repas, le p&rsquo;tit guillaume raconte sa journ\u00e9e \u00e0 sa grand-m\u00e8re. Ginette rit bien. Son petit-fils a de bien dr\u00f4les d&rsquo;id\u00e9es parfois.<\/p>\n\n\n\n<p>D&rsquo;ordinaire, le p&rsquo;tit Guillaume regarde un peu la t\u00e9l\u00e9vision le soir avec sa grand-m\u00e8re. Mais l\u00e0, il est si fatigu\u00e9 par l&rsquo;amusante journ\u00e9e qu&rsquo;il a pass\u00e9, qu&rsquo;il va directement se coucher.<\/p>\n\n\n\n<p><em>A bient\u00f4t les amis, pour de nouvelles aventures!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le p&rsquo;tit guillaume est un petit bonhomme de dix ans, aux cheveux blonds et aux yeux bruns. Dans sa vie, il n&rsquo;a pas trente-six hobbies. Ses passions: Star Wars, la p\u00eache et les vacances chez Ginette. Ginette, c&rsquo;est sa grand-m\u00e8re,&#8230; <a class=\"more-link\" href=\"https:\/\/graine-de-loute.ovh\/index.php\/2021\/08\/09\/les-aventures-du-pti-guillaume-la-partie-de-peche\/\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[23,21],"tags":[4,26],"class_list":["post-284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enfant","category-histoire","tag-aventures","tag-peche"],"jetpack_featured_media_url":"https:\/\/graine-de-loute.ovh\/wp-content\/uploads\/2021\/08\/petit-poisson.jpg","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdhhZc-4A","_links":{"self":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=284"}],"version-history":[{"count":0,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/posts\/284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/media\/291"}],"wp:attachment":[{"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/graine-de-loute.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}